{"id":3168,"date":"2021-05-24T12:15:52","date_gmt":"2021-05-24T12:15:52","guid":{"rendered":"https:\/\/alpina-galtuer.at\/?post_type=portfolio&#038;p=3168"},"modified":"2025-10-30T13:09:17","modified_gmt":"2025-10-30T13:09:17","slug":"ski-start-3","status":"publish","type":"portfolio","link":"https:\/\/alpina-galtuer.at\/en\/pauschalen\/ski-start-3\/","title":{"rendered":"Friends of Galt\u00fcr 1+1"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1jeo2j-e7c3ce68878448f0d7fa566d47e2b61a\">\n#top .hr.hr-invisible.av-1jeo2j-e7c3ce68878448f0d7fa566d47e2b61a{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-1jeo2j-e7c3ce68878448f0d7fa566d47e2b61a hr-invisible  avia-builder-el-0  el_before_av_one_full  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1fiskr-13056db513af40b50e9c6f189f26b237\">\n#top .flex_column.av-1fiskr-13056db513af40b50e9c6f189f26b237{\nmargin-top:0px;\nmargin-bottom:-50px;\n}\n.flex_column.av-1fiskr-13056db513af40b50e9c6f189f26b237{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n.responsive #top #wrap_all .flex_column.av-1fiskr-13056db513af40b50e9c6f189f26b237{\nmargin-top:0px;\nmargin-bottom:-50px;\n}\n<\/style>\n<div  class='flex_column av-1fiskr-13056db513af40b50e9c6f189f26b237 av_one_full  avia-builder-el-1  el_after_av_hr  el_before_av_layout_row  avia-builder-el-last  first flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kp5ffgt0-48d9f628d6d1e1102665f8deb7a87c4f\">\n#top .av-special-heading.av-kp5ffgt0-48d9f628d6d1e1102665f8deb7a87c4f{\npadding-bottom:0;\n}\nbody .av-special-heading.av-kp5ffgt0-48d9f628d6d1e1102665f8deb7a87c4f .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-kp5ffgt0-48d9f628d6d1e1102665f8deb7a87c4f .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-kp5ffgt0-48d9f628d6d1e1102665f8deb7a87c4f av-special-heading-h1 blockquote modern-quote  avia-builder-el-2  el_before_av_textblock  avia-builder-el-first '><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >Friends of Galt\u00fcr 1+1<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kp5fh350-b783f4899d1e17f00dfef4657b972fac\">\n#top .av_textblock_section.av-kp5fh350-b783f4899d1e17f00dfef4657b972fac .avia_textblock{\nfont-size:25px;\n}\n<\/style>\n<section  class='av_textblock_section av-kp5fh350-b783f4899d1e17f00dfef4657b972fac '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p style=\"font-weight: 400;\"><strong>From 14.12. to 20.12.2025<\/strong><\/p>\n<\/div><\/section><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av-layout-grid-1'  class='av-layout-grid-container av-18hjaj-175f5c50343a0f1816542d58afbe8fa7 entry-content-wrapper main_color av-flex-cells av-break-at-tablet  avia-builder-el-4  el_after_av_one_full  avia-builder-el-last  av-layout-grid-container-width grid-row-not-first  container_wrap fullsize'  >\n<div class='flex_cell av-134yf7-f0eb166878857704a455c2118d59d467 av-gridrow-cell av_one_half no_margin  avia-builder-el-5  el_before_av_cell_one_half  avia-builder-el-first '  ><div class='flex_cell_inner'><p><div class='flex_column_table av-wc55f-e6d069947dadca55d5e10fd89a6734ad sc-av_one_full av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-wc55f-e6d069947dadca55d5e10fd89a6734ad\">\n.flex_column.av-wc55f-e6d069947dadca55d5e10fd89a6734ad{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-wc55f-e6d069947dadca55d5e10fd89a6734ad av_one_full  avia-builder-el-6  el_before_av_one_full  avia-builder-el-first  first flex_column_table_cell av-equal-height-column av-align-bottom av-animated-generic left-to-right av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kp5fkesf-6f009cae86fccddd428f223d20849679\">\n.avia-image-container.av-kp5fkesf-6f009cae86fccddd428f223d20849679 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-kp5fkesf-6f009cae86fccddd428f223d20849679 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-kp5fkesf-6f009cae86fccddd428f223d20849679 av-styling- avia-align-center  avia-builder-el-7  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2183 avia-img-lazy-loading-not-2183 avia_image ' src=\"https:\/\/alpina-galtuer.at\/wp-content\/uploads\/2024\/11\/Skistart_Alpina_Galtuer_friends_galtuer_51.jpg\" alt='Zwei Personen Fahren auf der Skipiste und im Hintergrund sieht man die Berge.' title='Skistart_Alpina_Galtuer_friends_galtuer_5+1'  height=\"1000\" width=\"1500\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/alpina-galtuer.at\/wp-content\/uploads\/2024\/11\/Skistart_Alpina_Galtuer_friends_galtuer_51.jpg 1500w, https:\/\/alpina-galtuer.at\/wp-content\/uploads\/2024\/11\/Skistart_Alpina_Galtuer_friends_galtuer_51-300x200.jpg 300w, https:\/\/alpina-galtuer.at\/wp-content\/uploads\/2024\/11\/Skistart_Alpina_Galtuer_friends_galtuer_51-1030x687.jpg 1030w, https:\/\/alpina-galtuer.at\/wp-content\/uploads\/2024\/11\/Skistart_Alpina_Galtuer_friends_galtuer_51-768x512.jpg 768w, https:\/\/alpina-galtuer.at\/wp-content\/uploads\/2024\/11\/Skistart_Alpina_Galtuer_friends_galtuer_51-705x470.jpg 705w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/div><\/div><\/div><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-m3zn7igq-cc1f0ae2e1bd52d87d4f0f1d95606a72\">\n.flex_column.av-m3zn7igq-cc1f0ae2e1bd52d87d4f0f1d95606a72{\nbackground-color:#d3d1cb;\n}\n<\/style>\n<div  class='flex_column av-m3zn7igq-cc1f0ae2e1bd52d87d4f0f1d95606a72 av_one_full  avia-builder-el-8  el_after_av_one_full  avia-builder-el-last  ueberschrift-klein first flex_column_div  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-m3zn3jl6-0724a0be19a5b7cafcb9810a7581bf15\">\n#top .av-special-heading.av-m3zn3jl6-0724a0be19a5b7cafcb9810a7581bf15{\npadding-bottom:10px;\ncolor:#6a1219;\n}\nbody .av-special-heading.av-m3zn3jl6-0724a0be19a5b7cafcb9810a7581bf15 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-m3zn3jl6-0724a0be19a5b7cafcb9810a7581bf15 .special-heading-inner-border{\nborder-color:#6a1219;\n}\n.av-special-heading.av-m3zn3jl6-0724a0be19a5b7cafcb9810a7581bf15 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-m3zn3jl6-0724a0be19a5b7cafcb9810a7581bf15 av-special-heading-h2 custom-color-heading blockquote modern-quote  avia-builder-el-9  avia-builder-el-no-sibling '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >3 nights from \u20ac 270,- p.P.<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><\/div><\/p>\n<\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-nsdob-61170ca81c7f8a250b46e80c0f474189\">\n.flex_cell.av-nsdob-61170ca81c7f8a250b46e80c0f474189{\nvertical-align:middle;\n}\n.responsive #top #wrap_all .flex_cell.av-nsdob-61170ca81c7f8a250b46e80c0f474189{\npadding:30px 30px 30px 30px !important;\n}\n<\/style>\n<div class='flex_cell av-nsdob-61170ca81c7f8a250b46e80c0f474189 av-gridrow-cell av_one_half no_margin  avia-builder-el-10  el_after_av_cell_one_half  avia-builder-el-last  content-align-middle'  ><div class='flex_cell_inner'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-g7sej-c65cc738b6e732b33bdd1cd1da6c7989\">\n.flex_column.av-g7sej-c65cc738b6e732b33bdd1cd1da6c7989{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-g7sej-c65cc738b6e732b33bdd1cd1da6c7989 av_one_full  avia-builder-el-11  avia-builder-el-no-sibling  first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kp6q4awq-1f5f826c82986d2c3d4b94ba88310886\">\n#top .av_textblock_section.av-kp6q4awq-1f5f826c82986d2c3d4b94ba88310886 .avia_textblock{\nfont-size:25px;\n}\n<\/style>\n<section  class='av_textblock_section av-kp6q4awq-1f5f826c82986d2c3d4b94ba88310886 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p style=\"font-weight: 400;\"><strong>Start the season with us!<\/strong><\/p>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-kp5fjz51-9a202a753d113416fc30bd09c9aac95f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong>Start the season with us!<\/strong><\/p>\n<p>\u201cFRIENDS OF GALT\u00dcR &#8211; 1+1 Special\u201d<\/p>\n<p>One person pays for the ski pass, ski rental or private ski course, the second person enjoys a friendly and free of charge.<\/p>\n<p>Overnight stays incl. Alpina pampering board<\/p>\n<ul>\n<li>From 3 nights in a stylish double room<\/li>\n<li>Gourmet breakfast with regional delicacies<\/li>\n<li>cozy dinner with choice of menu<\/li>\n<li>Use of the hotel&#8217;s own wellness area<\/li>\n<li>Parking space directly at the hotel<\/li>\n<li>Services with ski pass from 1 +1 free of charge<\/li>\n<\/ul>\n<p>Prices excl. local tax (+ \u20ac 4.20 per day)<br \/>\nSurcharge for single room and double room deluxe<\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kp6q2nmf-2a7e6cbba375e126cb3175534c34f7f6\">\n#top .hr.hr-invisible.av-kp6q2nmf-2a7e6cbba375e126cb3175534c34f7f6{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-kp6q2nmf-2a7e6cbba375e126cb3175534c34f7f6 hr-invisible  avia-builder-el-14  el_after_av_textblock  el_before_av_button '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<div  class='avia-button-wrap av-m3znim5s-374c77bc41f8e0613a7503c6915cefb4-wrap avia-button-left  avia-builder-el-15  el_after_av_hr  avia-builder-el-last '><a href='https:\/\/alpina-galtuer.at\/en\/booking\/'  class='avia-button av-m3znim5s-374c77bc41f8e0613a7503c6915cefb4 av-link-btn avia-icon_select-no avia-size-large avia-position-left avia-color-theme-color'   aria-label=\"Book now\"><span class='avia_iconbox_title' >Book now<\/span><\/a><\/div><\/p><\/div>\n<\/div><\/div>\n<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>14.12. &#8211; 20.12.2025 \u2022 friends of galt\u00fcr 1+1<\/p>\n","protected":false},"author":2,"featured_media":2183,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"portfolio_entries":[22],"class_list":["post-3168","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-winter-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Friends of Galt\u00fcr 1+1 - Hotel Alpina Galt\u00fcr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alpina-galtuer.at\/en\/pauschalen\/ski-start-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Friends of Galt\u00fcr 1+1 - Hotel Alpina Galt\u00fcr\" \/>\n<meta property=\"og:description\" content=\"14.12. - 20.12.2025 \u2022 friends of galt\u00fcr 1+1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alpina-galtuer.at\/en\/pauschalen\/ski-start-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Alpina Galt\u00fcr\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T13:09:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alpina-galtuer.at\/wp-content\/uploads\/2024\/11\/Skistart_Alpina_Galtuer_friends_galtuer_51.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alpina-galtuer.at\\\/en\\\/pauschalen\\\/ski-start-3\\\/\",\"url\":\"https:\\\/\\\/alpina-galtuer.at\\\/en\\\/pauschalen\\\/ski-start-3\\\/\",\"name\":\"Friends of Galt\u00fcr 1+1 - Hotel Alpina Galt\u00fcr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alpina-galtuer.at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alpina-galtuer.at\\\/en\\\/pauschalen\\\/ski-start-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alpina-galtuer.at\\\/en\\\/pauschalen\\\/ski-start-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alpina-galtuer.at\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Skistart_Alpina_Galtuer_friends_galtuer_51.jpg\",\"datePublished\":\"2021-05-24T12:15:52+00:00\",\"dateModified\":\"2025-10-30T13:09:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alpina-galtuer.at\\\/en\\\/pauschalen\\\/ski-start-3\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alpina-galtuer.at\\\/en\\\/pauschalen\\\/ski-start-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/alpina-galtuer.at\\\/en\\\/pauschalen\\\/ski-start-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alpina-galtuer.at\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Skistart_Alpina_Galtuer_friends_galtuer_51.jpg\",\"contentUrl\":\"https:\\\/\\\/alpina-galtuer.at\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Skistart_Alpina_Galtuer_friends_galtuer_51.jpg\",\"width\":1500,\"height\":1000,\"caption\":\"Zwei Personen Fahren auf der Skipiste und im Hintergrund sieht man die Berge.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alpina-galtuer.at\\\/en\\\/pauschalen\\\/ski-start-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/alpina-galtuer.at\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Friends of Galt\u00fcr 1+1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alpina-galtuer.at\\\/#website\",\"url\":\"https:\\\/\\\/alpina-galtuer.at\\\/\",\"name\":\"Hotel Alpina Galt\u00fcr\",\"description\":\"Urlaub im Einklang mit der Natur\",\"publisher\":{\"@id\":\"https:\\\/\\\/alpina-galtuer.at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alpina-galtuer.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alpina-galtuer.at\\\/#organization\",\"name\":\"Hotel Alpina Galt\u00fcr\",\"url\":\"https:\\\/\\\/alpina-galtuer.at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/alpina-galtuer.at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alpina-galtuer.at\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/alpina-logo_Zeichenfla\u0308che-1-03.png\",\"contentUrl\":\"https:\\\/\\\/alpina-galtuer.at\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/alpina-logo_Zeichenfla\u0308che-1-03.png\",\"width\":2528,\"height\":1543,\"caption\":\"Hotel Alpina Galt\u00fcr\"},\"image\":{\"@id\":\"https:\\\/\\\/alpina-galtuer.at\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Friends of Galt\u00fcr 1+1 - Hotel Alpina Galt\u00fcr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alpina-galtuer.at\/en\/pauschalen\/ski-start-3\/","og_locale":"en_US","og_type":"article","og_title":"Friends of Galt\u00fcr 1+1 - Hotel Alpina Galt\u00fcr","og_description":"14.12. - 20.12.2025 \u2022 friends of galt\u00fcr 1+1","og_url":"https:\/\/alpina-galtuer.at\/en\/pauschalen\/ski-start-3\/","og_site_name":"Hotel Alpina Galt\u00fcr","article_modified_time":"2025-10-30T13:09:17+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/alpina-galtuer.at\/wp-content\/uploads\/2024\/11\/Skistart_Alpina_Galtuer_friends_galtuer_51.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alpina-galtuer.at\/en\/pauschalen\/ski-start-3\/","url":"https:\/\/alpina-galtuer.at\/en\/pauschalen\/ski-start-3\/","name":"Friends of Galt\u00fcr 1+1 - Hotel Alpina Galt\u00fcr","isPartOf":{"@id":"https:\/\/alpina-galtuer.at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alpina-galtuer.at\/en\/pauschalen\/ski-start-3\/#primaryimage"},"image":{"@id":"https:\/\/alpina-galtuer.at\/en\/pauschalen\/ski-start-3\/#primaryimage"},"thumbnailUrl":"https:\/\/alpina-galtuer.at\/wp-content\/uploads\/2024\/11\/Skistart_Alpina_Galtuer_friends_galtuer_51.jpg","datePublished":"2021-05-24T12:15:52+00:00","dateModified":"2025-10-30T13:09:17+00:00","breadcrumb":{"@id":"https:\/\/alpina-galtuer.at\/en\/pauschalen\/ski-start-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alpina-galtuer.at\/en\/pauschalen\/ski-start-3\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/alpina-galtuer.at\/en\/pauschalen\/ski-start-3\/#primaryimage","url":"https:\/\/alpina-galtuer.at\/wp-content\/uploads\/2024\/11\/Skistart_Alpina_Galtuer_friends_galtuer_51.jpg","contentUrl":"https:\/\/alpina-galtuer.at\/wp-content\/uploads\/2024\/11\/Skistart_Alpina_Galtuer_friends_galtuer_51.jpg","width":1500,"height":1000,"caption":"Zwei Personen Fahren auf der Skipiste und im Hintergrund sieht man die Berge."},{"@type":"BreadcrumbList","@id":"https:\/\/alpina-galtuer.at\/en\/pauschalen\/ski-start-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/alpina-galtuer.at\/en\/"},{"@type":"ListItem","position":2,"name":"Friends of Galt\u00fcr 1+1"}]},{"@type":"WebSite","@id":"https:\/\/alpina-galtuer.at\/#website","url":"https:\/\/alpina-galtuer.at\/","name":"Hotel Alpina Galt\u00fcr","description":"Urlaub im Einklang mit der Natur","publisher":{"@id":"https:\/\/alpina-galtuer.at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alpina-galtuer.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/alpina-galtuer.at\/#organization","name":"Hotel Alpina Galt\u00fcr","url":"https:\/\/alpina-galtuer.at\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/alpina-galtuer.at\/#\/schema\/logo\/image\/","url":"https:\/\/alpina-galtuer.at\/wp-content\/uploads\/2021\/05\/alpina-logo_Zeichenfla\u0308che-1-03.png","contentUrl":"https:\/\/alpina-galtuer.at\/wp-content\/uploads\/2021\/05\/alpina-logo_Zeichenfla\u0308che-1-03.png","width":2528,"height":1543,"caption":"Hotel Alpina Galt\u00fcr"},"image":{"@id":"https:\/\/alpina-galtuer.at\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/alpina-galtuer.at\/en\/wp-json\/wp\/v2\/portfolio\/3168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpina-galtuer.at\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/alpina-galtuer.at\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/alpina-galtuer.at\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alpina-galtuer.at\/en\/wp-json\/wp\/v2\/comments?post=3168"}],"version-history":[{"count":27,"href":"https:\/\/alpina-galtuer.at\/en\/wp-json\/wp\/v2\/portfolio\/3168\/revisions"}],"predecessor-version":[{"id":3768,"href":"https:\/\/alpina-galtuer.at\/en\/wp-json\/wp\/v2\/portfolio\/3168\/revisions\/3768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alpina-galtuer.at\/en\/wp-json\/wp\/v2\/media\/2183"}],"wp:attachment":[{"href":"https:\/\/alpina-galtuer.at\/en\/wp-json\/wp\/v2\/media?parent=3168"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alpina-galtuer.at\/en\/wp-json\/wp\/v2\/tags?post=3168"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/alpina-galtuer.at\/en\/wp-json\/wp\/v2\/portfolio_entries?post=3168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}